{"id":8591,"date":"2017-04-27T10:25:36","date_gmt":"2017-04-27T08:25:36","guid":{"rendered":"http:\/\/www.new.pdceurope.com\/fr\/?post_type=portfolio&#038;p=8591"},"modified":"2017-05-22T22:08:55","modified_gmt":"2017-05-22T20:08:55","slug":"caisse-maree-oso","status":"publish","type":"portfolio","link":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/","title":{"rendered":"Caisse Mar\u00e9e OSO"},"content":{"rendered":"","protected":false},"featured_media":9608,"menu_order":0,"template":"","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caisse Mar\u00e9e OSO - PDC Europe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Caisse Mar\u00e9e OSO - PDC Europe\" \/>\n<meta name=\"twitter:description\" content=\"Read more\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png\" \/>\n<meta name=\"twitter:site\" content=\"@PDC_Europe\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/\",\"url\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/\",\"name\":\"Caisse Mar\u00e9e OSO - PDC Europe\",\"isPartOf\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png\",\"datePublished\":\"2017-04-27T08:25:36+00:00\",\"dateModified\":\"2017-05-22T20:08:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage\",\"url\":\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png\",\"contentUrl\":\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png\",\"width\":900,\"height\":900,\"caption\":\"HORIZONTAL APPLICATION\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.pdceurope.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caisse Mar\u00e9e OSO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#website\",\"url\":\"https:\/\/www.pdceurope.com\/fr\/\",\"name\":\"PDC Europe\",\"description\":\"Cr\u00e9ation de solution de manchonnage\",\"publisher\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pdceurope.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#organization\",\"name\":\"PDC Europe\",\"url\":\"https:\/\/www.pdceurope.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/06\/LOGO-PDC-900X900.png\",\"contentUrl\":\"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/06\/LOGO-PDC-900X900.png\",\"width\":900,\"height\":900,\"caption\":\"PDC Europe\"},\"image\":{\"@id\":\"https:\/\/www.pdceurope.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/x.com\/PDC_Europe\",\"https:\/\/www.linkedin.com\/company\/pdc-europe\",\"https:\/\/www.youtube.com\/channel\/UCEx0SwTrsH0pnHQC7cXCCkw\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caisse Mar\u00e9e OSO - PDC Europe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/","twitter_card":"summary_large_image","twitter_title":"Caisse Mar\u00e9e OSO - PDC Europe","twitter_description":"Read more","twitter_image":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png","twitter_site":"@PDC_Europe","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/","url":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/","name":"Caisse Mar\u00e9e OSO - PDC Europe","isPartOf":{"@id":"https:\/\/www.pdceurope.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage"},"image":{"@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png","datePublished":"2017-04-27T08:25:36+00:00","dateModified":"2017-05-22T20:08:55+00:00","breadcrumb":{"@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#primaryimage","url":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png","contentUrl":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/05\/CAISSE-MARRE.png","width":900,"height":900,"caption":"HORIZONTAL APPLICATION"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pdceurope.com\/fr\/project\/caisse-maree-oso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.pdceurope.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Caisse Mar\u00e9e OSO"}]},{"@type":"WebSite","@id":"https:\/\/www.pdceurope.com\/fr\/#website","url":"https:\/\/www.pdceurope.com\/fr\/","name":"PDC Europe","description":"Cr\u00e9ation de solution de manchonnage","publisher":{"@id":"https:\/\/www.pdceurope.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pdceurope.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.pdceurope.com\/fr\/#organization","name":"PDC Europe","url":"https:\/\/www.pdceurope.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.pdceurope.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/06\/LOGO-PDC-900X900.png","contentUrl":"https:\/\/www.pdceurope.com\/wp-content\/uploads\/2017\/06\/LOGO-PDC-900X900.png","width":900,"height":900,"caption":"PDC Europe"},"image":{"@id":"https:\/\/www.pdceurope.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/PDC_Europe","https:\/\/www.linkedin.com\/company\/pdc-europe","https:\/\/www.youtube.com\/channel\/UCEx0SwTrsH0pnHQC7cXCCkw"]}]}},"_links":{"self":[{"href":"https:\/\/www.pdceurope.com\/fr\/wp-json\/wp\/v2\/portfolio\/8591"}],"collection":[{"href":"https:\/\/www.pdceurope.com\/fr\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.pdceurope.com\/fr\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pdceurope.com\/fr\/wp-json\/wp\/v2\/media\/9608"}],"wp:attachment":[{"href":"https:\/\/www.pdceurope.com\/fr\/wp-json\/wp\/v2\/media?parent=8591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}